{"id":279,"count":1,"description":"Der Landwirtschaft ist ein Zweig des Agrarsektors. Er besteht aus dem Anbau von Feldfr\u00fcchten im Freien, mit Ausnahme von Gem\u00fcse und Obst. Wir entwickeln viele verschiedene Folien und Verpackungen. Unser Sortiment umfasst Produkte, die einen Mehrwert f\u00fcr den Anbau, den Transport oder die Vermarktung von Ackerbauprodukten bieten.","link":"https:\/\/www.perfon.nl\/de\/marktubersicht\/agrar-gartenbau\/landwirtschaft\/","name":"Landwirtschaft","slug":"landwirtschaft","taxonomy":"product-market","parent":275,"meta":[],"acf":[],"yoast_head":"<title>Landwirtschaft Archieven - Perfon<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Landwirtschaft Archieven - Perfon\" \/>\n<meta property=\"og:description\" content=\"Der Landwirtschaft ist ein Zweig des Agrarsektors. Er besteht aus dem Anbau von Feldfr\u00fcchten im Freien, mit Ausnahme von Gem\u00fcse und Obst. Wir entwickeln viele verschiedene Folien und Verpackungen. Unser Sortiment umfasst Produkte, die einen Mehrwert f\u00fcr den Anbau, den Transport oder die Vermarktung von Ackerbauprodukten bieten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.perfon.nl\/de\/marktubersicht\/agrar-gartenbau\/landwirtschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"Perfon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.perfon.nl\\\/de\\\/marktubersicht\\\/agrar-gartenbau\\\/landwirtschaft\\\/\",\"url\":\"https:\\\/\\\/www.perfon.nl\\\/de\\\/marktubersicht\\\/agrar-gartenbau\\\/landwirtschaft\\\/\",\"name\":\"Landwirtschaft Archieven - Perfon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.perfon.nl\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.perfon.nl\\\/de\\\/marktubersicht\\\/agrar-gartenbau\\\/landwirtschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.perfon.nl\\\/de\\\/marktubersicht\\\/agrar-gartenbau\\\/landwirtschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.perfon.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agrar &amp; Gartenbau\",\"item\":\"https:\\\/\\\/www.perfon.nl\\\/de\\\/marktubersicht\\\/agrar-gartenbau\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Landwirtschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.perfon.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.perfon.nl\\\/de\\\/\",\"name\":\"Perfon\",\"description\":\"The sustainable innovator\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.perfon.nl\\\/de\\\/?suchanfrage={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>","yoast_head_json":{"title":"Landwirtschaft Archieven - Perfon","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Landwirtschaft Archieven - Perfon","og_description":"Der Landwirtschaft ist ein Zweig des Agrarsektors. Er besteht aus dem Anbau von Feldfr\u00fcchten im Freien, mit Ausnahme von Gem\u00fcse und Obst. Wir entwickeln viele verschiedene Folien und Verpackungen. Unser Sortiment umfasst Produkte, die einen Mehrwert f\u00fcr den Anbau, den Transport oder die Vermarktung von Ackerbauprodukten bieten.","og_url":"https:\/\/www.perfon.nl\/de\/marktubersicht\/agrar-gartenbau\/landwirtschaft\/","og_site_name":"Perfon","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.perfon.nl\/de\/marktubersicht\/agrar-gartenbau\/landwirtschaft\/","url":"https:\/\/www.perfon.nl\/de\/marktubersicht\/agrar-gartenbau\/landwirtschaft\/","name":"Landwirtschaft Archieven - Perfon","isPartOf":{"@id":"https:\/\/www.perfon.nl\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.perfon.nl\/de\/marktubersicht\/agrar-gartenbau\/landwirtschaft\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.perfon.nl\/de\/marktubersicht\/agrar-gartenbau\/landwirtschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.perfon.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Agrar &amp; Gartenbau","item":"https:\/\/www.perfon.nl\/de\/marktubersicht\/agrar-gartenbau\/"},{"@type":"ListItem","position":3,"name":"Landwirtschaft"}]},{"@type":"WebSite","@id":"https:\/\/www.perfon.nl\/de\/#website","url":"https:\/\/www.perfon.nl\/de\/","name":"Perfon","description":"The sustainable innovator","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.perfon.nl\/de\/?suchanfrage={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.perfon.nl\/de\/wp-json\/wp\/v2\/product-market\/279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.perfon.nl\/de\/wp-json\/wp\/v2\/product-market"}],"about":[{"href":"https:\/\/www.perfon.nl\/de\/wp-json\/wp\/v2\/taxonomies\/product-market"}],"up":[{"embeddable":true,"href":"https:\/\/www.perfon.nl\/de\/wp-json\/wp\/v2\/product-market\/275"}],"wp:post_type":[{"href":"https:\/\/www.perfon.nl\/de\/wp-json\/wp\/v2\/product?product-market=279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}